{"id":1734,"date":"2019-12-29T20:30:30","date_gmt":"2019-12-29T20:30:30","guid":{"rendered":"https:\/\/blog.id-direct.com\/?p=1734"},"modified":"2023-01-16T16:30:48","modified_gmt":"2023-01-16T16:30:48","slug":"5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants","status":"publish","type":"post","link":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/","title":{"rendered":"5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants"},"content":{"rendered":"\n<p>Vous est-il d\u00e9j\u00e0 arriv\u00e9 de rentrer plus t\u00f4t chez vous \u00e0 cause d&rsquo;un petit inconv\u00e9nient\u202f? Vous \u00eates-vous d\u00e9j\u00e0 senti contrari\u00e9 de devoir aller trop souvent aux toilettes lors d\u2019un voyage\u202f?&nbsp;<\/p>\n\n\n\n<p>Vous n\u2019aviez jamais imagin\u00e9 devoir radicalement&nbsp;changer votre mode de vie&nbsp;et devoir annuler des \u00e9v\u00e9nements sociaux. Ces d\u00e9ceptions sont totalement compr\u00e9hensibles, mais ne laissez pas pour autant les faiblesses de la vessie prendre le contr\u00f4le de toute votre vie.&nbsp;&nbsp;<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-surmonter-les-faiblesses-de-la-vessie\">Surmonter les faiblesses de la vessie&nbsp;&nbsp;<\/h2>\n\n\n\n<p>Si vous voulez vivre votre journ\u00e9e sans trop vous en soucier, il existe des&nbsp;<a href=\"https:\/\/blog.id-direct.com\/fr\/pourquoi-et-comment-puis-je-muscler-mon-plancher-pelvien\/\">exercices d\u00e9di\u00e9s au renforcement musculaire du plancher pelvien<\/a>&nbsp;ainsi que des postures de&nbsp;yoga&nbsp;qui peuvent vous aider \u00e0 g\u00e9rer vos petites fuites avec le temps. Des \u00e9tudes ont montr\u00e9 que ces exercices peuvent permettre de redonner de la force aux muscles affaiblis du plancher pelvien et de la vessie, faiblesses connues pour perturber la fonction urinaire normale chez l\u2019adulte.Pour renforcer ces muscles, vous devez apprendre&nbsp;<a href=\"https:\/\/blog.id-direct.com\/fr\/apprendre-a-se-detendre-pour-reduire-le-stress-2\/\">\u00e0 les d\u00e9tendre<\/a>.<sup>i<\/sup>&nbsp;<\/p>\n\n\n\n<p>Dans cet article, nous vous montrerons comment effectuer 5&nbsp;exercices ciblant les faiblesses de la vessie,&nbsp;y compris certaines postures de yoga, adapt\u00e9s aux d\u00e9butants.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"427\" src=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-saccroupir-1024x427.png\" alt=\"Comment s'accroupir\" class=\"wp-image-6332\" srcset=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-saccroupir-1024x427.png 1024w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-saccroupir-300x125.png 300w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-saccroupir-768x320.png 768w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-saccroupir-1170x488.png 1170w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-saccroupir-585x244.png 585w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-saccroupir.png 1435w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-les-squatsii\">Les squats<sup>ii<\/sup><strong><\/strong>&nbsp;<\/h2>\n\n\n\n<p>La musculature des ischio jambiers et des fessiers joue un r\u00f4le important sur le renforcement des muscles de la vessie. Les squats aident \u00e0 d\u00e9velopper ces muscles et \u00e0 soulager les tensions chroniques, ce qui en cons\u00e9quent peut traiter les petits soucis de fuites urinaires.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Pour ex\u00e9cuter des squats efficaces et tout en douceur, suivez les \u00e9tapes suivantes\u202f:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Tenez-vous droit les pieds \u00e9cart\u00e9s dans l&rsquo;alignement des hanches.&nbsp;<\/li>\n\n\n\n<li>Rentrez le ventre, sortez la poitrine et pliez les genoux tout en gardant le dos bien droit.&nbsp;<\/li>\n\n\n\n<li>Commencez \u00e0 descendre comme si vous deviez vous asseoir sur une chaise. Descendez le plus bas possible.&nbsp;<\/li>\n\n\n\n<li>Contractez les fessiers lorsque vous revenez \u00e0 la position debout. Gardez les jambes droites.&nbsp;&nbsp;<\/li>\n\n\n\n<li>R\u00e9p\u00e9tez ces \u00e9tapes pendant trois s\u00e9ries de 10 mouvements.&nbsp;<\/li>\n<\/ol>\n\n\n\n<p>N\u2019oubliez pas de vous concentrer sur votre souffle pendant l\u2019exercice et essayez de vous d\u00e9tendre. Pour de meilleurs r\u00e9sultats, effectuez des squats plusieurs fois par jour, notamment au lever, \u00e0 midi et avant de vous coucher. Si vous pr\u00e9f\u00e9rez le yoga, regardez cette&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=IXpJEqssze8\" target=\"_blank\" rel=\"noreferrer noopener\">vid\u00e9o<\/a>, qui pr\u00e9sente un exercice alternatif.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-exercices-de-kegeliii\">Exercices de Kegel<sup>iii<\/sup><strong><\/strong>&nbsp;<\/h2>\n\n\n\n<p>Les&nbsp;exercices de Kegel, destin\u00e9s aux hommes&nbsp;comme aux femmes, consistent \u00e0 contracter, retenir, puis rel\u00e2cher les sphincters, c.-\u00e0-d. les muscles qui contr\u00f4lent le d\u00e9bit d\u2019urine. Voici comment vous pouvez les effectuer convenablement\u202f:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Asseyez-vous dans une position confortable.&nbsp;<\/li>\n\n\n\n<li>Tout en expirant, contractez et maintenez vos sphincters pendant 3\u202fsecondes. Puis, pendant que vous inspirez, d\u00e9tendez-vous pendant 3\u202fsecondes.&nbsp;<\/li>\n\n\n\n<li>R\u00e9p\u00e9tez 10\u202ffois. Faites cet exercice deux fois par jour.&nbsp;<\/li>\n<\/ol>\n\n\n\n<p>Vous pouvez \u00e9galement effectuer vos exercices de Kegel lorsque vous adoptez la posture de la vache ou que vous \u00eates allong\u00e9. Pendant que vous contractez vos muscles, ajoutez 1 \u00e0 2 secondes lorsque vous effectuez l\u2019\u00e9tape\u202f2. Vous pouvez \u00e9galement augmenter le nombre de s\u00e9ries et le nombre de fois par jour que vous faites les&nbsp;exercices de Kegel pour les femmes&nbsp;et les hommes.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-contractez-et-relachez\">Contractez et rel\u00e2chez&nbsp;<\/h2>\n\n\n\n<p>Cet&nbsp;exercice, destin\u00e9 aux faiblesses de la vessie,&nbsp;consiste \u00e0 effectuer un mouvement de contraction et de rel\u00e2chement rapide dans le but d&rsquo;am\u00e9liorer la capacit\u00e9 de vos muscles pelviens \u00e0 r\u00e9pondre rapidement.&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Asseyez-vous ou couchez-vous dans une position confortable.&nbsp;<\/li>\n\n\n\n<li>Visualisez les muscles de votre plancher pelvien.&nbsp;<\/li>\n\n\n\n<li>Une fois que vous contr\u00f4lez ces muscles, contractez-les aussi rapidement que possible, puis rel\u00e2chez-les.&nbsp;<\/li>\n\n\n\n<li>Attendez 3\u202fsecondes avant de recommencer.&nbsp;<\/li>\n\n\n\n<li>R\u00e9p\u00e9tez jusqu\u2019\u00e0 20\u202ffois, deux fois par jour.&nbsp;<\/li>\n<\/ol>\n\n\n\n<p>Vous pouvez aussi pratiquer cet exercice chaque fois que vous toussez, \u00e9ternuez ou soulevez quelque chose de lourd. Ceci permet de renforcer davantage votre plancher pelvien et de lutter contre les petites fuites.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"431\" src=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-faire-le-Bridge-1024x431.png\" alt=\"Comment faire le pont\" class=\"wp-image-6327\" srcset=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-faire-le-Bridge-1024x431.png 1024w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-faire-le-Bridge-300x126.png 300w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-faire-le-Bridge-768x323.png 768w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-faire-le-Bridge-1170x493.png 1170w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-faire-le-Bridge-585x246.png 585w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Comment-faire-le-Bridge.png 1425w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-le-pont\">Le pont&nbsp;&nbsp;<\/h2>\n\n\n\n<p>\u00c9galement appel\u00e9 Setu Bandha au yoga, le pont est un exercice r\u00e9parateur et \u00e9nergisant qui peut activer votre plancher pelvien.&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Positionnez votre tapis et allongez-vous sur le dos. Vous pouvez aussi placer une couverture sous vos \u00e9paules pour pr\u00e9venir les douleurs du cou.&nbsp;<\/li>\n\n\n\n<li>Pliez les genoux tout en gardant les pieds \u00e0 plat sur le tapis, \u00e9cart\u00e9s dans l&rsquo;alignement des hanches.&nbsp;<\/li>\n\n\n\n<li>Placez vos bras sur les c\u00f4t\u00e9s, les paumes vers le haut.&nbsp;<\/li>\n\n\n\n<li>En expirant, appuyez la plante des pieds et les bras contre le sol.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Levez votre coccyx vers le haut, contractez les fesses et soulevez-les du tapis. Restez dans cette position pendant 8\u202fsecondes.&nbsp;<\/li>\n\n\n\n<li>Rel\u00e2chez. Reposez les fesses sur le tapis.&nbsp;<\/li>\n\n\n\n<li>R\u00e9p\u00e9tez 10 fois le mouvement pendant 2 s\u00e9ries.&nbsp;<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-posture-de-la-deesse-du-sommeiliv\">Posture de la d\u00e9esse du sommeil<sup>iv<\/sup><strong><\/strong>&nbsp;<\/h2>\n\n\n\n<p>\u00c9galement appel\u00e9e&nbsp;<a href=\"https:\/\/www.youtube.com\/watch?v=FnhjJxEzsoQ\" target=\"_blank\" rel=\"noreferrer noopener\">Supta Baddha Konasana<\/a>, c\u2019est une posture de yoga classique et r\u00e9paratrice qui peut agir sur l\u2019ensemble des muscles du plancher pelvien.&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Couchez-vous sur le dos.&nbsp;<\/li>\n\n\n\n<li>Pliez les genoux tout en gardant les pieds \u00e0 plat sur le sol.&nbsp;<\/li>\n\n\n\n<li>\u00c9cartez les genoux de chaque c\u00f4t\u00e9 et placez vos plantes de pieds l\u2019une contre l\u2019autre.&nbsp;<\/li>\n\n\n\n<li>Laissez vos bras adopter une position confortable, au-dessus de la t\u00eate, sur les c\u00f4t\u00e9s, ou sur vos cuisses.&nbsp;<\/li>\n\n\n\n<li>Imaginez que vos genoux soient si l\u00e9gers qu\u2019ils donnent l\u2019impression de flotter jusqu\u2019au plafond. Laissez votre aine s&rsquo;enfoncer profond\u00e9ment dans la r\u00e9gion pelvienne. Alors que votre aine s\u2019enfonce, vos genoux en font de m\u00eame.&nbsp;<\/li>\n\n\n\n<li>Maintenez cette posture pendant 5 \u00e0 10 minutes (r\u00e9glez un minuteur). Respirez naturellement tout au long de cet exercice.&nbsp;<\/li>\n\n\n\n<li>Pour quitter cette position, attrapez vos cuisses et aidez-les \u00e0 se joindre. Roulez sur le c\u00f4t\u00e9 et poussez-vous vers le haut.&nbsp;<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-vous-remarquerez-une-difference-apres-3-a-6-mois\">Vous remarquerez une diff\u00e9rence apr\u00e8s 3 \u00e0 6 mois&nbsp;<\/h2>\n\n\n\n<p>Nous le savons bien, les r\u00e9sultats n&rsquo;apparaissent pas en une nuit. Vous commencerez \u00e0 constater la diff\u00e9rence apr\u00e8s avoir pratiqu\u00e9 ces exercices sur une p\u00e9riode allant de 3 \u00e0 6\u202fmois. Vous pourrez retrouver le contr\u00f4le de votre vessie, vous aurez moins de petits incidents embarrassants et vous serez capable de faire plus de r\u00e9p\u00e9titions lors d&rsquo;une s\u00e9rie d&rsquo;exercices. Ils peuvent aussi vous aider \u00e0 limiter vos risques de complications associ\u00e9es, telles que la d\u00e9tresse \u00e9motionnelle et le manque de sommeil.&nbsp;<\/p>\n\n\n\n<p>Si vous \u00e9prouvez un&nbsp;petit inconfort&nbsp;pendant que vous faites vos exercices, portez une&nbsp;<a href=\"https:\/\/www.id-direct.com\/franceb2c\/fr\/category\/iD-Light\/IDLight.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">protection l\u00e9g\u00e8re<\/a>. Nous avons toute une gamme de protections, mini, normales, extra, maxi jusqu\u2019\u00e0 super. Pour toute question relative \u00e0 nos protections, n\u2019h\u00e9sitez pas \u00e0&nbsp;<a href=\"https:\/\/www.id-direct.com\/franceb2c\/fr\/page\/contact.html\">nous contacter<\/a>&nbsp;ou cliquez <a href=\"https:\/\/www.id-direct.com\/franceb2c\/fr\/index.html\">ici<\/a>.&nbsp;<\/p>\n\n\n\n<p>En savoir plus sur le mode de vie \u00e0 adopter en cas de faiblesses de la vessie&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-very-light-gray-color has-vivid-cyan-blue-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.id-direct.com\/franceb2c\/fr\/index.html\"> Voir les produits&nbsp; <\/a><\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Les exercices de vessie peuvent aider \u00e0 am\u00e9liorer une vessie faible. D\u00e9couvrez tous les exercices de renforcement de la vessie et d\u00e9couvrez comment contr\u00f4ler les fuites urinaires<\/p>\n","protected":false},"author":1,"featured_media":6307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1342,1827,2113],"tags":[],"class_list":["post-1734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-femmesfr","category-exercises-hommes-hommes-fr","category-hommesfr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants<\/title>\n<meta name=\"description\" content=\"Les exercices de vessie peuvent aider \u00e0 am\u00e9liorer une vessie faible. D\u00e9couvrez tous les exercices de renforcement de la vessie et d\u00e9couvrez comment contr\u00f4ler les fuites urinaires\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants\" \/>\n<meta property=\"og:description\" content=\"Les exercices de vessie peuvent aider \u00e0 am\u00e9liorer une vessie faible. D\u00e9couvrez tous les exercices de renforcement de la vessie et d\u00e9couvrez comment contr\u00f4ler les fuites urinaires\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/\" \/>\n<meta property=\"og:site_name\" content=\"iD Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iDInvisibleSolutionsForaLifeinFullViewUK\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-29T20:30:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-16T16:30:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Femme-fait-de-lexercice.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2866\" \/>\n\t<meta property=\"og:image:height\" content=\"1198\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"iddirect\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"iddirect\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/\"},\"author\":{\"name\":\"iddirect\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#\\\/schema\\\/person\\\/abaa9575b453f8387f3e02330357299b\"},\"headline\":\"5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants\",\"datePublished\":\"2019-12-29T20:30:30+00:00\",\"dateModified\":\"2023-01-16T16:30:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/\"},\"wordCount\":1196,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Femme-fait-de-lexercice.png\",\"articleSection\":[\"Femmes\",\"Exercises\",\"Hommes\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/\",\"name\":\"5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Femme-fait-de-lexercice.png\",\"datePublished\":\"2019-12-29T20:30:30+00:00\",\"dateModified\":\"2023-01-16T16:30:48+00:00\",\"description\":\"Les exercices de vessie peuvent aider \u00e0 am\u00e9liorer une vessie faible. D\u00e9couvrez tous les exercices de renforcement de la vessie et d\u00e9couvrez comment contr\u00f4ler les fuites urinaires\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Femme-fait-de-lexercice.png\",\"contentUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/12\\\/Femme-fait-de-lexercice.png\",\"width\":2866,\"height\":1198,\"caption\":\"Femme fait de l'exercice\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/\",\"name\":\"iD Blog\",\"description\":\"Des conseils d'experts sur l'incontinence\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#organization\",\"name\":\"Ontex BVBA\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ontex_Logotype_Normal.png\",\"contentUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ontex_Logotype_Normal.png\",\"width\":4642,\"height\":1777,\"caption\":\"Ontex BVBA\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/iDInvisibleSolutionsForaLifeinFullViewUK\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6Xt_hNdoAmVmHvMHpNxiIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#\\\/schema\\\/person\\\/abaa9575b453f8387f3e02330357299b\",\"name\":\"iddirect\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants","description":"Les exercices de vessie peuvent aider \u00e0 am\u00e9liorer une vessie faible. D\u00e9couvrez tous les exercices de renforcement de la vessie et d\u00e9couvrez comment contr\u00f4ler les fuites urinaires","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/","og_locale":"fr_FR","og_type":"article","og_title":"5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants","og_description":"Les exercices de vessie peuvent aider \u00e0 am\u00e9liorer une vessie faible. D\u00e9couvrez tous les exercices de renforcement de la vessie et d\u00e9couvrez comment contr\u00f4ler les fuites urinaires","og_url":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/","og_site_name":"iD Blog","article_publisher":"https:\/\/www.facebook.com\/iDInvisibleSolutionsForaLifeinFullViewUK\/","article_published_time":"2019-12-29T20:30:30+00:00","article_modified_time":"2023-01-16T16:30:48+00:00","og_image":[{"width":2866,"height":1198,"url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Femme-fait-de-lexercice.png","type":"image\/png"}],"author":"iddirect","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"iddirect","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/#article","isPartOf":{"@id":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/"},"author":{"name":"iddirect","@id":"https:\/\/blog.id-direct.com\/fr\/#\/schema\/person\/abaa9575b453f8387f3e02330357299b"},"headline":"5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants","datePublished":"2019-12-29T20:30:30+00:00","dateModified":"2023-01-16T16:30:48+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/"},"wordCount":1196,"commentCount":0,"publisher":{"@id":"https:\/\/blog.id-direct.com\/fr\/#organization"},"image":{"@id":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Femme-fait-de-lexercice.png","articleSection":["Femmes","Exercises","Hommes"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/","url":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/","name":"5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants","isPartOf":{"@id":"https:\/\/blog.id-direct.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/#primaryimage"},"image":{"@id":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Femme-fait-de-lexercice.png","datePublished":"2019-12-29T20:30:30+00:00","dateModified":"2023-01-16T16:30:48+00:00","description":"Les exercices de vessie peuvent aider \u00e0 am\u00e9liorer une vessie faible. D\u00e9couvrez tous les exercices de renforcement de la vessie et d\u00e9couvrez comment contr\u00f4ler les fuites urinaires","breadcrumb":{"@id":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/#primaryimage","url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Femme-fait-de-lexercice.png","contentUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/12\/Femme-fait-de-lexercice.png","width":2866,"height":1198,"caption":"Femme fait de l'exercice"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.id-direct.com\/fr\/5-exercices-dedies-aux-faiblesses-de-la-vessie-adaptes-aux-debutants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.id-direct.com\/fr\/"},{"@type":"ListItem","position":2,"name":"5 exercices d\u00e9di\u00e9s aux faiblesses de la vessie adapt\u00e9s aux d\u00e9butants"}]},{"@type":"WebSite","@id":"https:\/\/blog.id-direct.com\/fr\/#website","url":"https:\/\/blog.id-direct.com\/fr\/","name":"iD Blog","description":"Des conseils d'experts sur l'incontinence","publisher":{"@id":"https:\/\/blog.id-direct.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.id-direct.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.id-direct.com\/fr\/#organization","name":"Ontex BVBA","url":"https:\/\/blog.id-direct.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.id-direct.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/07\/Ontex_Logotype_Normal.png","contentUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/07\/Ontex_Logotype_Normal.png","width":4642,"height":1777,"caption":"Ontex BVBA"},"image":{"@id":"https:\/\/blog.id-direct.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iDInvisibleSolutionsForaLifeinFullViewUK\/","https:\/\/www.youtube.com\/channel\/UC6Xt_hNdoAmVmHvMHpNxiIA"]},{"@type":"Person","@id":"https:\/\/blog.id-direct.com\/fr\/#\/schema\/person\/abaa9575b453f8387f3e02330357299b","name":"iddirect"}]}},"_links":{"self":[{"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/posts\/1734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/comments?post=1734"}],"version-history":[{"count":0,"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/posts\/1734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/media\/6307"}],"wp:attachment":[{"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/media?parent=1734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/categories?post=1734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/tags?post=1734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}