{"id":5867,"count":1,"description":"","link":"https:\/\/blog.id-direct.com\/fr\/category\/hommesfr\/mental-health-men-fr\/","name":"Mental Health","slug":"mental-health-men-fr","taxonomy":"category","parent":2113,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mental Health Archives &#183; iD Blog<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Mental Health\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.id-direct.com\/fr\/category\/hommesfr\/mental-health-men-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"iD Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2023\/03\/id_blog_Homepage-Banner-1024x920.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/category\\\/hommesfr\\\/mental-health-men-fr\\\/\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/category\\\/hommesfr\\\/mental-health-men-fr\\\/\",\"name\":\"Mental Health Archives &#183; iD Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/category\\\/hommesfr\\\/mental-health-men-fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/category\\\/hommesfr\\\/mental-health-men-fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hommes\",\"item\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/category\\\/hommesfr\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mental Health\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/\",\"name\":\"iD Blog\",\"description\":\"Des conseils d'experts sur l'incontinence\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#organization\",\"name\":\"Ontex BVBA\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ontex_Logotype_Normal.png\",\"contentUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ontex_Logotype_Normal.png\",\"width\":4642,\"height\":1777,\"caption\":\"Ontex BVBA\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/iDInvisibleSolutionsForaLifeinFullViewUK\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6Xt_hNdoAmVmHvMHpNxiIA\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mental Health Archives &#183; iD Blog","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Archives des Mental Health","og_url":"https:\/\/blog.id-direct.com\/fr\/category\/hommesfr\/mental-health-men-fr\/","og_site_name":"iD Blog","og_image":[{"width":1024,"height":920,"url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2023\/03\/id_blog_Homepage-Banner-1024x920.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.id-direct.com\/fr\/category\/hommesfr\/mental-health-men-fr\/","url":"https:\/\/blog.id-direct.com\/fr\/category\/hommesfr\/mental-health-men-fr\/","name":"Mental Health Archives &#183; iD Blog","isPartOf":{"@id":"https:\/\/blog.id-direct.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/blog.id-direct.com\/fr\/category\/hommesfr\/mental-health-men-fr\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.id-direct.com\/fr\/category\/hommesfr\/mental-health-men-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.id-direct.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Hommes","item":"https:\/\/blog.id-direct.com\/fr\/category\/hommesfr\/"},{"@type":"ListItem","position":3,"name":"Mental Health"}]},{"@type":"WebSite","@id":"https:\/\/blog.id-direct.com\/fr\/#website","url":"https:\/\/blog.id-direct.com\/fr\/","name":"iD Blog","description":"Des conseils d'experts sur l'incontinence","publisher":{"@id":"https:\/\/blog.id-direct.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.id-direct.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/blog.id-direct.com\/fr\/#organization","name":"Ontex BVBA","url":"https:\/\/blog.id-direct.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.id-direct.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/07\/Ontex_Logotype_Normal.png","contentUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/07\/Ontex_Logotype_Normal.png","width":4642,"height":1777,"caption":"Ontex BVBA"},"image":{"@id":"https:\/\/blog.id-direct.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iDInvisibleSolutionsForaLifeinFullViewUK\/","https:\/\/www.youtube.com\/channel\/UC6Xt_hNdoAmVmHvMHpNxiIA"]}]}},"_links":{"self":[{"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/categories\/5867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/categories\/2113"}],"wp:post_type":[{"href":"https:\/\/blog.id-direct.com\/fr\/wp-json\/wp\/v2\/posts?categories=5867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}