{"id":8359,"date":"2022-02-14T14:00:00","date_gmt":"2022-02-14T14:00:00","guid":{"rendered":"https:\/\/blog.id-direct.com\/?p=8359"},"modified":"2022-02-14T14:00:06","modified_gmt":"2022-02-14T14:00:06","slug":"infection-urinaire-recidivante","status":"publish","type":"post","link":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/","title":{"rendered":"Quelles sont les causes d\u2019une infection urinaire r\u00e9cidivante ?"},"content":{"rendered":"\n<p class=\"has-background\" style=\"background-color:#f3f3f3\">Les <strong>infections urinaires<\/strong> (IU) peuvent \u00eatre tr\u00e8s inconfortables et frustrantes, surtout si elles <strong>se r\u00e9p\u00e8tent sans cesse<\/strong>. Mais quelles peuvent \u00eatre les causes d\u2019une <strong>infection urinaire r\u00e9cidivante<\/strong>&nbsp;?<\/p>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"425\" src=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Docteur-examinant-la-vessie-1024x425.png\" alt=\"Docteur examinant la vessie\" class=\"wp-image-8309\" srcset=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Docteur-examinant-la-vessie-1024x425.png 1024w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Docteur-examinant-la-vessie-300x124.png 300w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Docteur-examinant-la-vessie-768x318.png 768w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Docteur-examinant-la-vessie-1170x485.png 1170w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Docteur-examinant-la-vessie-585x243.png 585w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Docteur-examinant-la-vessie.png 1401w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Les infections urinaires, qu\u2019est-ce que c\u2019est&nbsp;?<\/h2>\n\n\n\n<p><a href=\"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-ui\/\">Les infections urinaires<\/a> (IU) touchent les <strong>voies urinaires<\/strong>, y compris la <strong>vessie<\/strong> (<strong>cystite<\/strong>), l\u2019<strong>ur\u00e8tre<\/strong> (<strong>ur\u00e9trite<\/strong>) et les <strong>reins <\/strong>(<strong>infection r\u00e9nale<\/strong>)<sup>1<\/sup>. La plupart des infections concernent les <strong>voies urinaires inf\u00e9rieures<\/strong> (vessie et ur\u00e8tre)<sup>2<\/sup>, les infections r\u00e9nales \u00e9tant plus rares. Parmi les <strong>sympt\u00f4mes <\/strong>les plus courants, on retrouve&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>envie <\/strong>pressante et fr\u00e9quente <strong>d\u2019uriner<\/strong>,<\/li><li>une <strong>douleur <\/strong>ou une <strong>sensation de br\u00fblure<\/strong> lors de la miction&nbsp;;<\/li><li>une urine <strong>odorante<\/strong>, <strong>trouble <\/strong>ou pr\u00e9sentant des <strong>saignements<\/strong><sup>3<\/sup>.<\/li><\/ul>\n\n\n\n<p>Certaines personnes sont <strong>plus sujettes<\/strong> aux infections urinaires. Vous vous demandez peut-\u00eatre\u00a0: <strong>quelles peuvent \u00eatre les causes d\u2019une infection urinaire r\u00e9cidivante<\/strong>\u00a0?<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Des facteurs li\u00e9s au style de vie peuvent \u00eatre \u00e0 l\u2019origine d\u2019une infection urinaire r\u00e9cidivante<\/h2>\n\n\n\n<p>Certains facteurs de risque li\u00e9s au mode de vie peuvent entra\u00eener des <strong>infections urinaires r\u00e9cidivantes<\/strong>, notamment&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>l\u2019utilisation de <strong>produits parfum\u00e9s <\/strong>au niveau de vos parties intimes&nbsp;;<\/li><li>le fait de <strong>se retenir <\/strong>d\u2019uriner&nbsp;;<\/li><li>ne pas <a href=\"https:\/\/blog.id-direct.com\/fr-be\/3-boissons-saines-qui-preserveront-votre-vessie-pendant-les-fetes\/\">boire<\/a> suffisamment d\u2019<strong>eau<\/strong>&nbsp;;<\/li><li>le fait de ne pas vous essuyer <strong>d\u2019avant en arri\u00e8re<\/strong> aux toilettes, ce qui peut introduire des <strong>bact\u00e9ries <\/strong>dans les voies urinaires&nbsp;;<\/li><li>le port de sous-v\u00eatements <strong>en mati\u00e8re synth\u00e9tique<\/strong> ou de v\u00eatements <strong>serr\u00e9s<\/strong><sup>4<\/sup>, ce qui signifie que les organes g\u00e9nitaux ne restent pas <strong>propres et au sec<\/strong><sup>5<\/sup>&nbsp;;<\/li><li>l\u2019utilisation excessive de <strong>tampons<\/strong><sup>6<\/sup>&nbsp;;<\/li><li>les <strong>rapports sexuels <\/strong>trop fr\u00e9quents<sup>7<\/sup>&nbsp;;<\/li><li>un nouveau <strong>partenaire sexuel<\/strong><sup>8<\/sup>&nbsp;;<\/li><li>l\u2019utilisation d\u2019un <strong>diaphragme contraceptif <\/strong>ou de <strong>pr\u00e9servatifs avec spermicide<\/strong><sup>9<\/sup>.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"425\" src=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Condition-medicale-1024x425.png\" alt=\"Condition m\u00e9dicale\" class=\"wp-image-8304\" srcset=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Condition-medicale-1024x425.png 1024w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Condition-medicale-300x124.png 300w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Condition-medicale-768x318.png 768w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Condition-medicale-1170x485.png 1170w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Condition-medicale-585x243.png 585w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Condition-medicale.png 1401w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Facteurs m\u00e9dicaux susceptibles peuvent \u00eatre \u00e0 l\u2019origine d\u2019une infection urinaire r\u00e9cidivante<\/h2>\n\n\n\n<p>Outre les facteurs li\u00e9s au mode de vie mentionn\u00e9s ci-dessus, certains facteurs <strong>m\u00e9dicaux <\/strong>peuvent provoquer des infections urinaires r\u00e9cidivantes&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>des ant\u00e9c\u00e9dents d\u2019infections urinaires pendant la <strong>pr\u00e9-m\u00e9nopause<\/strong> ou l\u2019<strong>enfance<\/strong>&nbsp;;<\/li><li>des <strong>ant\u00e9c\u00e9dents d\u2019infections<\/strong> urinaires&nbsp;;<\/li><li>une <strong>atrophie vulvo-vaginale<\/strong><sup>10<\/sup> (amincissement, ass\u00e8chement et inflammation de la <strong>paroi vaginale<\/strong>)<sup>11<\/sup>&nbsp;;<\/li><li>certaines maladies, comme les <strong>calculs r\u00e9naux<\/strong>, qui bloquent les voies urinaires&nbsp;;<\/li><li>l\u2019incapacit\u00e9 \u00e0 <strong>vider <\/strong>correctement la vessie&nbsp;;<\/li><li>du <strong>diab\u00e8te<\/strong>&nbsp;;<\/li><li>un <strong>syst\u00e8me immunitaire faible<\/strong>&nbsp;;<\/li><li>une <strong>hypertrophie de la prostate<\/strong>&nbsp;;<\/li><li>un <strong>cath\u00e9ter <\/strong>(un tube dans l\u2019ur\u00e8tre pour \u00e9vacuer l\u2019urine)<sup>12<\/sup>&nbsp;;<\/li><li>la constipation chez les <a href=\"https:\/\/blog.id-direct.com\/fr-be\/3-boissons-saines-qui-preserveront-votre-vessie-pendant-les-fetes\/\">enfants<\/a>. Les infections urinaires, r\u00e9cidivantes ou non, peuvent entra\u00eener des <strong>complications <\/strong>chez l\u2019<strong>enfant. <\/strong><em>Consultez donc toujours un professionnel de sant\u00e9 si vous pensez que votre petit a une infection urinaire<\/em><sup>13<\/sup>&nbsp;;<\/li><li>le fait d\u2019<a href=\"https:\/\/blog.id-direct.com\/fr-be\/fuites-urinaires-pendant-grossesse\/\"><strong>\u00eatre enceinte<\/strong><\/a>. Le risque que l\u2019infection se propage aux <strong>reins <\/strong>est plus grand et peut entra\u00eener des <strong>complications<\/strong>. <em>Consultez donc toujours un professionnel de sant\u00e9 si vous \u00eates enceinte et que vous pensez avoir une infection urinaire<\/em>&nbsp;;<\/li><li>l\u2019<strong>incontinence f\u00e9cale<\/strong>&nbsp;;<\/li><li>la <strong>m\u00e9nopause<\/strong> (lorsque les r\u00e8gles d\u2019une femme s\u2019arr\u00eatent et qu\u2019il y a des <strong>changements hormonaux<\/strong>)&nbsp;;<\/li><li>les <strong>proc\u00e9dures m\u00e9dicales<\/strong> au niveau des voies urinaires&nbsp;;<\/li><li>un changement de <strong>bact\u00e9ries <\/strong>dans votre vagin (toutes les vulves h\u00e9bergent naturellement des bact\u00e9ries <strong>b\u00e9n\u00e9fiques <\/strong>capables de pr\u00e9venir les maladies) caus\u00e9 par une <strong>utilisation d\u2019antibiotiques excessive<\/strong><sup>14<\/sup>&nbsp;;<\/li><li>l\u2019<strong>anatomie f\u00e9minine<\/strong>. Les femmes ont des <strong>ur\u00e8tres <\/strong>plus courts et plus proches de l\u2019<strong>anus<\/strong>, ce qui favorise le passage des bact\u00e9ries&nbsp;;<\/li><li>des <strong>troubles<\/strong> de l\u2019appareil urinaire<sup>15<\/sup>.<\/li><\/ul>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"425\" src=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Arretez-de-retourner-UTI-1024x425.png\" alt=\"Arr\u00eatez de retourner UTI\" class=\"wp-image-8299\" srcset=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Arretez-de-retourner-UTI-1024x425.png 1024w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Arretez-de-retourner-UTI-300x124.png 300w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Arretez-de-retourner-UTI-768x318.png 768w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Arretez-de-retourner-UTI-1170x485.png 1170w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Arretez-de-retourner-UTI-585x243.png 585w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Arretez-de-retourner-UTI.png 1401w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Complications et pr\u00e9vention de l\u2019infection urinaire r\u00e9cidivante<\/h2>\n\n\n\n<p>L\u2019infection urinaire r\u00e9cidivante, qui se manifeste chez les <strong>femmes deux fois ou plus en six mois<\/strong> ou <strong>quatre ou plus en un an<\/strong>, peuvent entra\u00eener des <strong>complications<\/strong>.<sup>16<\/sup> Celles-ci incluent&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>une <strong>infection des reins<\/strong>&nbsp;;<\/li><li>des <strong>abc\u00e8s <\/strong>au niveau des <strong>reins<\/strong>&nbsp;;<\/li><li><strong>fonction r\u00e9nale<\/strong> d\u00e9faillante&nbsp;;<\/li><li>une <strong>insuffisance <\/strong>r\u00e9nale&nbsp;;<\/li><li>une <strong>urosepsie<\/strong><sup>17<\/sup> (septic\u00e9mie dans les reins)<sup>18<\/sup>.<\/li><\/ul>\n\n\n\n<p><em>Il est donc extr\u00eamement important que vous parliez \u00e0 votre professionnel de sant\u00e9 si vous pensez que vous souffrez d\u2019infections urinaires r\u00e9cidivantes. <\/em>En attendant, vous pouvez essayer d\u2019appliquer ce qui suit pour \u00e9viter l\u2019infection urinaire r\u00e9cidivante&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>prendre du <strong>D-mannose<\/strong> ou des <a href=\"https:\/\/blog.id-direct.com\/fr-be\/canneberge-infection-urinaire\/\"><strong>comprim\u00e9s de canneberge<\/strong><\/a> (chez les femmes de moins de 65&nbsp;ans)&nbsp;;<\/li><li>boire beaucoup d\u2019<strong>eau<\/strong>&nbsp;;<\/li><li>uriner d\u00e8s que possible apr\u00e8s un <strong>rapport sexuel<\/strong><sup>19<\/sup>&nbsp;;<\/li><li>passer aux <strong>serviettes hygi\u00e9niques<\/strong> si vous avez une infection urinaire pendant vos <strong>r\u00e8gles <\/strong>et veillez \u00e0 les changer <strong>r\u00e9guli\u00e8rement<\/strong><sup>20<\/sup>&nbsp;;<\/li><li>changer diff\u00e9rents aspects du <a href=\"https:\/\/blog.id-direct.com\/fr-be\/remedes-infections-urinaires-maison\/\"><strong>mode de vie<\/strong><\/a>, notamment en \u00e9vitant la <a href=\"https:\/\/blog.id-direct.com\/fr-be\/cafe-decafeine-vessie\/\"><strong>caf\u00e9ine<\/strong><\/a> et l\u2019<a href=\"https:\/\/blog.id-direct.com\/fr-be\/alcool-vessie-effets\/\"><strong>alcool<\/strong><\/a><sup>21<\/sup>, et en augmentant votre apport en <strong>vitamine&nbsp;C<\/strong><sup>22<\/sup>&nbsp;;<\/li><li>\u00e9vitez la <a href=\"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-et-baignade\/\"><strong>natation<\/strong><\/a> <strong>en mer<\/strong><sup>23<\/sup> et veillez \u00e0 <strong>bien vous rincer<\/strong> apr\u00e8s une s\u00e9ance de natation en piscine (car le <strong>chlore <\/strong>peut irriter les voies urinaires)<sup>24<\/sup>.<\/li><\/ul>\n\n\n\n<p>Vous pouvez \u00e9galement envisager d\u2019utiliser des <strong>protections d\u2019incontinence <\/strong>pour g\u00e9rer vos sympt\u00f4mes si vous avez des <strong>fuites<\/strong>. Essayez la gamme de <a href=\"https:\/\/www.id-direct.com\/belgiumb2c\/fr\/index.html\"><strong>protections<\/strong> et de <strong>sous-v\u00eatements<\/strong><\/a> d\u2019iD, <strong>discr\u00e8tes<\/strong>, <strong>confortables <\/strong>et <strong>approuv\u00e9es par des dermatologues<\/strong>.<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 ces explications et conseils, nous esp\u00e9rons vous avoir donn\u00e9 toutes les informations dont vous aviez besoin pour comprendre l\u2019infection urinaire r\u00e9cidivante et comment la <strong>pr\u00e9venir<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h1 class=\"wp-block-heading\" id=\"h-sources\">Sources<\/h1>\n\n\n\n<p class=\"has-small-font-size\"><sup>1 <\/sup>\u201cUrinary tract infections (UTIs)\u201d, <em>NHS, <\/em>18 November 2020, Source: https:\/\/www.nhs.uk\/conditions\/urinary-tract-infections-uti\/<br><sup>2 <\/sup>\u201cUrinary tract infection (UTI)\u201d, <em>Mayo Clinic Staff, <\/em>n.d., Source: https:\/\/www.mayoclinic.org\/diseases-conditions\/urinary-tract-infection\/symptoms-causes\/syc-20353447<br><sup>3 <\/sup>\u201cWhat to know about urinary tract infections\u201d, <em>James McIntosh, <\/em>6 November 2018, Source: https:\/\/www.medicalnewstoday.com\/articles\/189953<br><sup>4 <\/sup>\u201cUrinary tract infections in adults\u201d, <em>NHS, <\/em>12 December 2017, Source: https:\/\/www.nhs.uk\/conditions\/urinary-tract-infection-adults\/pages\/introduction.aspx\/amp\/#causes<br><sup>5 <\/sup>\u201cUrinary tract infections (UTIs)\u201d, <em>NHS, <\/em>18 November 2020, Source: https:\/\/www.nhs.uk\/conditions\/urinary-tract-infections-utis\/<br><sup>6 <\/sup>\u201cWhat to know about urinary tract infections\u201d, <em>James McIntosh, <\/em>6 November 2018, Source: https:\/\/www.medicalnewstoday.com\/articles\/189953<br><sup>7 <\/sup>\u201cRisk factors and predisposing conditions for urinary tract infection\u201d, <em>Oscar Storme, Jos\u00e9 Tir\u00e1n Saucedo, Arturo Garcia-Mora, Manuel Dehesa-D\u00e1vila, and Kurt G. Naber, <\/em>2 May 2019, Source: https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6502981\/<br><sup>8 <\/sup>\u201cUrinary tract infection (UTI)\u201d, <em>Mayo Clinic Staff, <\/em>n.d., Source: https:\/\/www.mayoclinic.org\/diseases-conditions\/urinary-tract-infection\/symptoms-causes\/syc-20353447<br><sup>9 <\/sup>\u201cUrinary tract infections (UTIs)\u201d, <em>NHS, <\/em>18 November 2020, Source: https:\/\/www.nhs.uk\/conditions\/urinary-tract-infections-utis\/<br><sup>10 <\/sup>\u201cRisk factors and predisposing conditions for urinary tract infection\u201d, <em>Oscar Storme, Jos\u00e9 Tir\u00e1n Saucedo, Arturo Garcia-Mora, Manuel Dehesa-D\u00e1vila, and Kurt G. Naber, <\/em>2 May 2019, Source: https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC6502981\/<br><sup>11 <\/sup>\u201cVaginal atrophy\u201d, <em>Mayo Clinic Staff, <\/em>n.d., Source: https:\/\/www.mayoclinic.org\/diseases-conditions\/vaginal-atrophy\/symptoms-causes\/syc-20352288<br><sup>12 <\/sup>\u201cUrinary tract infections in adults\u201d, <em>NHS, <\/em>12 December 2017, Source: https:\/\/www.nhs.uk\/conditions\/urinary-tract-infection-adults\/pages\/introduction.aspx\/amp\/#causes<br><sup>13 <\/sup>\u201cUrinary tract infections (UTIs)\u201d, <em>NHS, <\/em>18 November 2020, Source: https:\/\/www.nhs.uk\/conditions\/urinary-tract-infections-utis\/<br><sup>14 <\/sup>\u201cWhat to know about urinary tract infections\u201d, <em>James McIntosh, <\/em>6 November 2018, Source: https:\/\/www.medicalnewstoday.com\/articles\/189953<br><sup>15 <\/sup>\u201cUrinary tract infection (UTI)\u201d, <em>Mayo Clinic Staff, <\/em>n.d., Source: https:\/\/www.mayoclinic.org\/diseases-conditions\/urinary-tract-infection\/symptoms-causes\/syc-20353447<br><sup>16<\/sup> Ibid<br><sup>17 <\/sup>\u201cWhat are the complications?\u201d, <em>NICE, <\/em>June 2021, Source: https:\/\/cks.nice.org.uk\/topics\/urinary-tract-infection-lower-women\/background-information\/complications\/<br><sup>18 <\/sup>\u201cWhat Is Urosepsis?\u201d, <em>Dan Brennan, <\/em>7 June 2021, Source: https:\/\/www.webmd.com\/a-to-z-guides\/what-is-urosepsis<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les infections urinaires (IU) peuvent \u00eatre tr\u00e8s inconfortables et frustrantes, surtout si elles se r\u00e9p\u00e8tent sans cesse. Mais quelles peuvent \u00eatre les causes d\u2019une infection urinaire r\u00e9cidivante&nbsp;?<\/p>\n","protected":false},"author":1,"featured_media":8320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1829,1836,1837,1828],"tags":[],"class_list":["post-8359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-femmesfrbe","category-incontinence-causes-femmes","category-incontinence-causes-hommes","category-hommesfrbe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les causes de l\u2019infection urinaire r\u00e9cidivante<\/title>\n<meta name=\"description\" content=\"\u00cates-vous sujet\u00b7te aux infections urinaires ? Si vous souhaitez savoir ce qui cause une infection urinaire r\u00e9cidivante, poursuivez votre lecture.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelles sont les causes d\u2019une infection urinaire r\u00e9cidivante ?\" \/>\n<meta property=\"og:description\" content=\"\u00cates-vous sujet\u00b7te aux infections urinaires ? Si vous souhaitez savoir ce qui cause une infection urinaire r\u00e9cidivante, poursuivez votre lecture.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/\" \/>\n<meta property=\"og:site_name\" content=\"iD Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iDInvisibleSolutionsForaLifeinFullViewUK\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-14T14:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-14T14:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Homme-sans-papier-toilette.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1433\" \/>\n\t<meta property=\"og:image:height\" content=\"599\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"iddirect\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"iddirect\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/\"},\"author\":{\"name\":\"iddirect\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#\\\/schema\\\/person\\\/abaa9575b453f8387f3e02330357299b\"},\"headline\":\"Quelles sont les causes d\u2019une infection urinaire r\u00e9cidivante ?\",\"datePublished\":\"2022-02-14T14:00:00+00:00\",\"dateModified\":\"2022-02-14T14:00:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/\"},\"wordCount\":1233,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Homme-sans-papier-toilette.png\",\"articleSection\":[\"Femmes\",\"Incontinence &amp; Causes\",\"Incontinence &amp; Causes\",\"Hommes\"],\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/\",\"name\":\"Les causes de l\u2019infection urinaire r\u00e9cidivante\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Homme-sans-papier-toilette.png\",\"datePublished\":\"2022-02-14T14:00:00+00:00\",\"dateModified\":\"2022-02-14T14:00:06+00:00\",\"description\":\"\u00cates-vous sujet\u00b7te aux infections urinaires ? Si vous souhaitez savoir ce qui cause une infection urinaire r\u00e9cidivante, poursuivez votre lecture.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Homme-sans-papier-toilette.png\",\"contentUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/Homme-sans-papier-toilette.png\",\"width\":1433,\"height\":599,\"caption\":\"Homme sans papier toilette\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/infection-urinaire-recidivante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quelles sont les causes d\u2019une infection urinaire r\u00e9cidivante ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#website\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/\",\"name\":\"iD Blog\",\"description\":\"Des conseils d'experts sur l'incontinence\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#organization\",\"name\":\"Ontex BVBA\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ontex_Logotype_Normal.png\",\"contentUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ontex_Logotype_Normal.png\",\"width\":4642,\"height\":1777,\"caption\":\"Ontex BVBA\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/iDInvisibleSolutionsForaLifeinFullViewUK\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6Xt_hNdoAmVmHvMHpNxiIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#\\\/schema\\\/person\\\/abaa9575b453f8387f3e02330357299b\",\"name\":\"iddirect\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les causes de l\u2019infection urinaire r\u00e9cidivante","description":"\u00cates-vous sujet\u00b7te aux infections urinaires ? Si vous souhaitez savoir ce qui cause une infection urinaire r\u00e9cidivante, poursuivez votre lecture.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/","og_locale":"fr_FR","og_type":"article","og_title":"Quelles sont les causes d\u2019une infection urinaire r\u00e9cidivante ?","og_description":"\u00cates-vous sujet\u00b7te aux infections urinaires ? Si vous souhaitez savoir ce qui cause une infection urinaire r\u00e9cidivante, poursuivez votre lecture.","og_url":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/","og_site_name":"iD Blog","article_publisher":"https:\/\/www.facebook.com\/iDInvisibleSolutionsForaLifeinFullViewUK\/","article_published_time":"2022-02-14T14:00:00+00:00","article_modified_time":"2022-02-14T14:00:06+00:00","og_image":[{"width":1433,"height":599,"url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Homme-sans-papier-toilette.png","type":"image\/png"}],"author":"iddirect","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"iddirect","Dur\u00e9e de lecture est.":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/#article","isPartOf":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/"},"author":{"name":"iddirect","@id":"https:\/\/blog.id-direct.com\/fr-be\/#\/schema\/person\/abaa9575b453f8387f3e02330357299b"},"headline":"Quelles sont les causes d\u2019une infection urinaire r\u00e9cidivante ?","datePublished":"2022-02-14T14:00:00+00:00","dateModified":"2022-02-14T14:00:06+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/"},"wordCount":1233,"commentCount":0,"publisher":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/#organization"},"image":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Homme-sans-papier-toilette.png","articleSection":["Femmes","Incontinence &amp; Causes","Incontinence &amp; Causes","Hommes"],"inLanguage":"fr-BE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/","url":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/","name":"Les causes de l\u2019infection urinaire r\u00e9cidivante","isPartOf":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/#primaryimage"},"image":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Homme-sans-papier-toilette.png","datePublished":"2022-02-14T14:00:00+00:00","dateModified":"2022-02-14T14:00:06+00:00","description":"\u00cates-vous sujet\u00b7te aux infections urinaires ? Si vous souhaitez savoir ce qui cause une infection urinaire r\u00e9cidivante, poursuivez votre lecture.","breadcrumb":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/#primaryimage","url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Homme-sans-papier-toilette.png","contentUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2022\/02\/Homme-sans-papier-toilette.png","width":1433,"height":599,"caption":"Homme sans papier toilette"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.id-direct.com\/fr-be\/infection-urinaire-recidivante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.id-direct.com\/fr-be\/"},{"@type":"ListItem","position":2,"name":"Quelles sont les causes d\u2019une infection urinaire r\u00e9cidivante ?"}]},{"@type":"WebSite","@id":"https:\/\/blog.id-direct.com\/fr-be\/#website","url":"https:\/\/blog.id-direct.com\/fr-be\/","name":"iD Blog","description":"Des conseils d'experts sur l'incontinence","publisher":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.id-direct.com\/fr-be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/blog.id-direct.com\/fr-be\/#organization","name":"Ontex BVBA","url":"https:\/\/blog.id-direct.com\/fr-be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/blog.id-direct.com\/fr-be\/#\/schema\/logo\/image\/","url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/07\/Ontex_Logotype_Normal.png","contentUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/07\/Ontex_Logotype_Normal.png","width":4642,"height":1777,"caption":"Ontex BVBA"},"image":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iDInvisibleSolutionsForaLifeinFullViewUK\/","https:\/\/www.youtube.com\/channel\/UC6Xt_hNdoAmVmHvMHpNxiIA"]},{"@type":"Person","@id":"https:\/\/blog.id-direct.com\/fr-be\/#\/schema\/person\/abaa9575b453f8387f3e02330357299b","name":"iddirect"}]}},"_links":{"self":[{"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/posts\/8359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/comments?post=8359"}],"version-history":[{"count":0,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/posts\/8359\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/media\/8320"}],"wp:attachment":[{"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/media?parent=8359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/categories?post=8359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/tags?post=8359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}