{"id":3436,"date":"2020-11-17T16:16:25","date_gmt":"2020-11-17T16:16:25","guid":{"rendered":"https:\/\/blog.id-direct.com\/?p=3436"},"modified":"2021-11-25T16:38:19","modified_gmt":"2021-11-25T16:38:19","slug":"le-masque-facial-de-protection-id-care","status":"publish","type":"post","link":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/","title":{"rendered":"Le masque facial de protection iD Care\u202f: pourquoi et comment le porter"},"content":{"rendered":"\n<p>Les derni\u00e8res ann\u00e9es ont apport\u00e9 une s\u00e9rie d&rsquo;\u00e9v\u00e9nements et de changements inattendus. Que vous travailliez encore de\u00a0chez vous ou que vous soyez revenu \u00e0 la semi-normalit\u00e9 de la vie de bureau, nous avons tous un nouveau point commun\u202f: le\u00a0<strong>masque facial de protection<\/strong>. Dans la plupart des pays, il est d\u00e9sormais obligatoire d&rsquo;en porter un dans les espaces publics clos, tels\u00a0que les supermarch\u00e9s, les magasins, dans certains lieux de travail et dans les transports publics. Chez\u00a0iD, nous nous soucions toujours de votre bien-\u00eatre. Dans cet article, nous vous pr\u00e9sentons notre\u00a0<strong>masque facial de protection\u00a0iD\u00a0Care<\/strong>\u00a0et vous expliquons\u00a0comment l&rsquo;utiliser.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quand-et-comment-portez-vous-un-masque-facial-de-protection\">Quand et comment portez-vous un masque facial de protection\u202f?&nbsp;<\/h2>\n\n\n\n<p>En fonction du pays dans lequel vous vivez, la r\u00e9glementation concernant le moment o\u00f9 vous devez porter un masque facial de protection peut diff\u00e9rer. D&rsquo;une mani\u00e8re g\u00e9n\u00e9rale, l&rsquo;Organisation mondiale de la Sant\u00e9 (OMS) recommande le port de diff\u00e9rents types de masques, dont les&nbsp;<strong>masques chirurgicaux<\/strong>, qui peuvent \u00eatre utilis\u00e9s dans les situations suivantes\u202f:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Vous \u00eates un professionnel de sant\u00e9.&nbsp;<\/li><li>Vous avez les sympt\u00f4mes de la COVID-19.&nbsp;<\/li><li>Vous vous occupez d&rsquo;une personne suspect\u00e9e de COVID-19.<sup>1<\/sup>&nbsp;<\/li><\/ul>\n\n\n\n<p>L&rsquo;OMS&nbsp;recommande \u00e9galement au minimum que les personnes qui ne pr\u00e9sentent&nbsp;<strong>pas<\/strong>&nbsp;les sympt\u00f4mes de la COVID-19 portent un masque facial en tissu dans les endroits o\u00f9 la distance sociale ne peut \u00eatre respect\u00e9e.<sup>2<\/sup>&nbsp;<em>iD&nbsp;vous recommande de suivre les directives gouvernementales du pays dans lequel vous vivez.&nbsp;<\/em>&nbsp;<\/p>\n\n\n\n<p>Pour mettre correctement votre&nbsp;masque facial de protection\u202f:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>lavez-vous d&rsquo;abord les mains avec de l&rsquo;eau et du savon ou une solution hydroalcoolique\u202f;<\/li><li>placez-le sur votre visage de fa\u00e7on \u00e0 recouvrir le nez, la bouche et le menton\u202f;&nbsp;<\/li><li>ajustez-le sur les c\u00f4t\u00e9s de votre visage pour ne pas laisser d&rsquo;espace\u202f;&nbsp;<\/li><li>si le masque dispose d&rsquo;une barrette nasale, pincez-la pour ajuster le masque facial sur le visage\u202f;&nbsp;<\/li><li>assurez-vous qu&rsquo;il ne vous emp\u00eache pas de respirer correctement\u202f;&nbsp;<\/li><li>\u00e9vitez de toucher votre masque lorsque vous le portez et retirez-le en&nbsp;retirant les \u00e9lastiques tour-de-t\u00eate vers le haut du cr\u00e2ne, puis&nbsp;lavez-vous les mains ou d\u00e9sinfectez-les.<sup>3<\/sup>&nbsp;<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-quel-type-de-masque-facial-de-protection-devez-vous-porter\">Quel type de masque facial de protection devez-vous porter\u202f?&nbsp;<\/h2>\n\n\n\n<p>Il existe principalement&nbsp;<strong>trois<\/strong>&nbsp;types de masques.&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Les masques en tissus<\/strong>\u202f: \u00e9galement connus sous le nom de masques barri\u00e8res, masques en tissu, masques grand public. Ils incluent les masques faits&nbsp;\u00e0 la main, les \u00e9charpes et les autres protections du visage. Ils offrent une protection minimale, mais, lorsqu&rsquo;ils sont combin\u00e9s au respect de la distanciation sociale, peuvent aider \u00e0 contenir la dispersion de gouttelettes de la part du porteur du masque&nbsp;facial. Ils retiennent les gouttelettes lib\u00e9r\u00e9es lorsque la personne \u00e9ternue, tousse ou parle. Lorsque le masque est mouill\u00e9 ou sale, vous devez en changer pour un propre.<sup>4<\/sup>&nbsp;Suivez les instructions de lavage des fabricants pour vous assurer que vous le faites correctement.<\/li><li><strong>Les masques&nbsp;<\/strong><strong>m\u00e9dicaux ou&nbsp;<\/strong><strong>chirurgicaux<\/strong>\u202f:<strong>&nbsp;<\/strong>dits masques \u00ab\u202fanti-projections\u202f\u00bb. Ils sont \u00e0 usage unique, souples et jetables. Ils ne doivent pas \u00eatre port\u00e9s au-del\u00e0 de quatre heures. Ils prot\u00e8gent le porteur des \u00e9claboussures (lorsqu&rsquo;ils sont de type\u202fIIR), des a\u00e9rosols et des gouttelettes \u00e0 grosses particules. Ils permettent aussi retenir la dispersion de gouttelettes provenant du porteur du masque facial de protection. Il existe trois niveaux de protection\u202f: type\u202fI, type\u202fII et type\u202fIIR par ordre d&rsquo;efficacit\u00e9 croissante.<sup>5<\/sup>&nbsp;&nbsp;<\/li><li><strong>Les masques respiratoires<\/strong>\u202f:<strong>&nbsp;<\/strong>les N95 et FFP2 sont les masques respiratoires les plus courants. Ils offrent un niveau de protection sup\u00e9rieur \u00e0 celui des masques chirurgicaux ou en tissu, parce qu&rsquo;ils peuvent filtrer les petites particules comme les grosses. Ils sont \u00e0 usage unique et&nbsp;peuvent \u00eatre port\u00e9s pendant environ 24\u202fheures. Ils sont con\u00e7us pour bloquer 95\u202f% des particules ou des liquides pouvant entrer en contact avec votre visage. Ils ne sont&nbsp;<strong>pas&nbsp;<\/strong>destin\u00e9s au grand public et doivent \u00eatre r\u00e9serv\u00e9s aux professionnels de sant\u00e9.<sup>6<\/sup>&nbsp;&nbsp;<\/li><\/ul>\n\n\n\n<p>Le masque le plus commun\u00e9ment recommand\u00e9 est le&nbsp;<strong>masque&nbsp;<\/strong><strong>m\u00e9dical<\/strong>.<strong>&nbsp;<\/strong>Il est plus particuli\u00e8rement conseill\u00e9 pour les professionnels travaillant en h\u00f4pital ou \u00e0 domicile. Dans cette optique,&nbsp;iD&nbsp;a&nbsp;lanc\u00e9&nbsp;le&nbsp;<strong>masque facial de protection&nbsp;<\/strong><strong>iD<\/strong><strong>&nbsp;Care<\/strong><strong>&nbsp;Mask<\/strong>.&nbsp;&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pourquoi-choisir-le-masque-facial-de-protection-id-care-mask\">Pourquoi choisir le masque facial de protection&nbsp;iD&nbsp;Care&nbsp;Mask\u202f?&nbsp;<\/h2>\n\n\n\n<p>iD&nbsp;Care a con\u00e7u son masque facial de protection en gardant toujours \u00e0 l&rsquo;esprit votre confort et votre s\u00e9curit\u00e9. Les principaux avantages pour vous sont\u202f:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>le masque facial de protection&nbsp;iD&nbsp;Care est sans latex et approuv\u00e9 par les dermatologues.&nbsp;&nbsp;<\/li><li>Il est produit en Belgique, garantissant un niveau \u00e9lev\u00e9 de qualit\u00e9, de service et de livraison.&nbsp;&nbsp;<\/li><li>Le masque facial de protection&nbsp;iD&nbsp;Care couvre une plus grande surface et vous assure ainsi une protection plus large.<\/li><li>Il s&rsquo;agit d&rsquo;un&nbsp;<strong>masque&nbsp;m\u00e9dical&nbsp;jetable de type IIR<\/strong>&nbsp;qui vous offrira la s\u00e9curit\u00e9 maximale qu&rsquo;un masque de ce type peut offrir. Le masque facial de protection&nbsp;iD&nbsp;Care&nbsp;Mask&nbsp;cr\u00e9e une&nbsp;barri\u00e8re contre les gouttelettes fines et les \u00e9claboussures, et est g\u00e9n\u00e9ralement utilis\u00e9 dans des environnements de soins complexes, tels que les salles d&rsquo;op\u00e9ration.&nbsp;&nbsp;<\/li><li>Au lieu d&rsquo;\u00e9lastiques \u00e0 passer derri\u00e8re les oreilles, qui peuvent devenir inconfortables, le masque facial de protection&nbsp;iD&nbsp;Care est dot\u00e9 de deux grands&nbsp;\u00e9lastiques&nbsp;plats qui s&rsquo;adaptent autour de la t\u00eate et du cou. Cela assure un bon ajustement au niveau de la bouche et du nez, offrant ainsi une protection et un confort maximum.&nbsp;&nbsp;<\/li><li>Les masques sont emball\u00e9s de mani\u00e8re hygi\u00e9nique dans une bo\u00eete de 50\u202fpi\u00e8ces refermable.&nbsp;&nbsp;<\/li><\/ul>\n\n\n\n<p>Chez&nbsp;iD, nous nous engageons \u00e0 vous offrir des solutions de haute qualit\u00e9, confortables et approuv\u00e9es par les dermatologues pour vos besoins m\u00e9dicaux. Pour acheter nos masques&nbsp;<strong>faciaux de protection&nbsp;iD&nbsp;Care<\/strong>, cliquez&nbsp;ici.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.id-direct.com\/belgiumb2c\/fr\/newsletter.html?utm_source=Blog_BEFR&amp;utm_medium=article&amp;utm_campaign=Blog_BEFR&amp;utm_id=Blog_BEFR\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"1024\" height=\"174\" src=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2021\/10\/CTA_Email_FRA-1024x174.png\" alt=\"R\u00e9duction registration email\" class=\"wp-image-5987\" srcset=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2021\/10\/CTA_Email_FRA-1024x174.png 1024w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2021\/10\/CTA_Email_FRA-300x51.png 300w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2021\/10\/CTA_Email_FRA-768x131.png 768w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2021\/10\/CTA_Email_FRA-1170x199.png 1170w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2021\/10\/CTA_Email_FRA-585x100.png 585w, https:\/\/blog.id-direct.com\/wp-content\/uploads\/2021\/10\/CTA_Email_FRA.png 1433w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p>Pour t\u00e9l\u00e9charger les instructions d&rsquo;utilisation, cliquez&nbsp;<a href=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2020\/12\/Ontex_IFU-iDCareMask-FINAL-beFR.pdf\">ici<\/a>.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>(1) \u201cCoronavirus disease (COVID-19) advice for the public: When and how to use masks\u201d, World Health Organization, 5 August 2020, Source: https:\/\/www.who.int\/emergencies\/diseases\/novel-coronavirus-2019\/advice-for-public\/when-and-how-to-use-masks<\/p>\n\n\n\n<p>(2) Ibid.<\/p>\n\n\n\n<p>(3) \u201cHow to Wear Masks\u201d, CDC, 7 August 2020, Source: https:\/\/www.cdc.gov\/coronavirus\/2019-ncov\/prevent-getting-sick\/how-to-wear-cloth-face-coverings.html<\/p>\n\n\n\n<p>(4) \u201cWhich type of face mask is most effective against COVID-19?\u201d, Janelle Ringer, 11 August 2020, Source: https:\/\/news.llu.edu\/health-wellness\/which-type-of-face-mask-most-effective-against-covid-19<\/p>\n\n\n\n<p>(5) Ibid. Additional information taken from iD\u2019s presentation: \u201ciD Care Masks: Type of Masks\u201d<\/p>\n\n\n\n<p>(6) Ibid.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vie a bien chang\u00e9 en 2020 et nous souhaitons vous accompagner dans cette transition, avec notre masque facial de protection iD Care.<\/p>\n","protected":false},"author":1,"featured_media":3454,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[1829,1828,1831],"tags":[],"class_list":["post-3436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-femmesfrbe","category-hommesfrbe","category-aidesoignantsfrbe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le masque facial de protection\u202f: pourquoi et comment le porter\u00a0<\/title>\n<meta name=\"description\" content=\"La vie a bien chang\u00e9 en 2020 et nous souhaitons vous accompagner dans cette transition, avec notre masque facial de protection iD Care.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le masque facial de protection iD Care\u202f: pourquoi et comment le porter\" \/>\n<meta property=\"og:description\" content=\"La vie a bien chang\u00e9 en 2020 et nous souhaitons vous accompagner dans cette transition, avec notre masque facial de protection iD Care.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/\" \/>\n<meta property=\"og:site_name\" content=\"iD Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/iDInvisibleSolutionsForaLifeinFullViewUK\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-17T16:16:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-25T16:38:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2020\/11\/iD-Care-Mask_doctorpatient.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"iddirect\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"iddirect\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/\"},\"author\":{\"name\":\"iddirect\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#\\\/schema\\\/person\\\/abaa9575b453f8387f3e02330357299b\"},\"headline\":\"Le masque facial de protection iD Care\u202f: pourquoi et comment le porter\",\"datePublished\":\"2020-11-17T16:16:25+00:00\",\"dateModified\":\"2021-11-25T16:38:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/\"},\"wordCount\":1170,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/iD-Care-Mask_doctorpatient.png\",\"articleSection\":[\"Femmes\",\"Hommes\",\"Aide Soignants\"],\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/\",\"name\":\"Le masque facial de protection\u202f: pourquoi et comment le porter\u00a0\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/iD-Care-Mask_doctorpatient.png\",\"datePublished\":\"2020-11-17T16:16:25+00:00\",\"dateModified\":\"2021-11-25T16:38:19+00:00\",\"description\":\"La vie a bien chang\u00e9 en 2020 et nous souhaitons vous accompagner dans cette transition, avec notre masque facial de protection iD Care.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/iD-Care-Mask_doctorpatient.png\",\"contentUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/iD-Care-Mask_doctorpatient.png\",\"width\":1170,\"height\":780,\"caption\":\"doctor & patient with iD Care Mask\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/le-masque-facial-de-protection-id-care\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le masque facial de protection iD Care\u202f: pourquoi et comment le porter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#website\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/\",\"name\":\"iD Blog\",\"description\":\"Des conseils d'experts sur l'incontinence\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#organization\",\"name\":\"Ontex BVBA\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ontex_Logotype_Normal.png\",\"contentUrl\":\"https:\\\/\\\/blog.id-direct.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/Ontex_Logotype_Normal.png\",\"width\":4642,\"height\":1777,\"caption\":\"Ontex BVBA\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/iDInvisibleSolutionsForaLifeinFullViewUK\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6Xt_hNdoAmVmHvMHpNxiIA\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.id-direct.com\\\/fr-be\\\/#\\\/schema\\\/person\\\/abaa9575b453f8387f3e02330357299b\",\"name\":\"iddirect\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le masque facial de protection\u202f: pourquoi et comment le porter\u00a0","description":"La vie a bien chang\u00e9 en 2020 et nous souhaitons vous accompagner dans cette transition, avec notre masque facial de protection iD Care.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/","og_locale":"fr_FR","og_type":"article","og_title":"Le masque facial de protection iD Care\u202f: pourquoi et comment le porter","og_description":"La vie a bien chang\u00e9 en 2020 et nous souhaitons vous accompagner dans cette transition, avec notre masque facial de protection iD Care.","og_url":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/","og_site_name":"iD Blog","article_publisher":"https:\/\/www.facebook.com\/iDInvisibleSolutionsForaLifeinFullViewUK\/","article_published_time":"2020-11-17T16:16:25+00:00","article_modified_time":"2021-11-25T16:38:19+00:00","og_image":[{"width":1170,"height":780,"url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2020\/11\/iD-Care-Mask_doctorpatient.png","type":"image\/png"}],"author":"iddirect","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"iddirect","Dur\u00e9e de lecture est.":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/#article","isPartOf":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/"},"author":{"name":"iddirect","@id":"https:\/\/blog.id-direct.com\/fr-be\/#\/schema\/person\/abaa9575b453f8387f3e02330357299b"},"headline":"Le masque facial de protection iD Care\u202f: pourquoi et comment le porter","datePublished":"2020-11-17T16:16:25+00:00","dateModified":"2021-11-25T16:38:19+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/"},"wordCount":1170,"commentCount":0,"publisher":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/#organization"},"image":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2020\/11\/iD-Care-Mask_doctorpatient.png","articleSection":["Femmes","Hommes","Aide Soignants"],"inLanguage":"fr-BE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/","url":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/","name":"Le masque facial de protection\u202f: pourquoi et comment le porter\u00a0","isPartOf":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/#primaryimage"},"image":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2020\/11\/iD-Care-Mask_doctorpatient.png","datePublished":"2020-11-17T16:16:25+00:00","dateModified":"2021-11-25T16:38:19+00:00","description":"La vie a bien chang\u00e9 en 2020 et nous souhaitons vous accompagner dans cette transition, avec notre masque facial de protection iD Care.","breadcrumb":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/#primaryimage","url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2020\/11\/iD-Care-Mask_doctorpatient.png","contentUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2020\/11\/iD-Care-Mask_doctorpatient.png","width":1170,"height":780,"caption":"doctor & patient with iD Care Mask"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.id-direct.com\/fr-be\/le-masque-facial-de-protection-id-care\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.id-direct.com\/fr-be\/"},{"@type":"ListItem","position":2,"name":"Le masque facial de protection iD Care\u202f: pourquoi et comment le porter"}]},{"@type":"WebSite","@id":"https:\/\/blog.id-direct.com\/fr-be\/#website","url":"https:\/\/blog.id-direct.com\/fr-be\/","name":"iD Blog","description":"Des conseils d'experts sur l'incontinence","publisher":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.id-direct.com\/fr-be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/blog.id-direct.com\/fr-be\/#organization","name":"Ontex BVBA","url":"https:\/\/blog.id-direct.com\/fr-be\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/blog.id-direct.com\/fr-be\/#\/schema\/logo\/image\/","url":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/07\/Ontex_Logotype_Normal.png","contentUrl":"https:\/\/blog.id-direct.com\/wp-content\/uploads\/2019\/07\/Ontex_Logotype_Normal.png","width":4642,"height":1777,"caption":"Ontex BVBA"},"image":{"@id":"https:\/\/blog.id-direct.com\/fr-be\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/iDInvisibleSolutionsForaLifeinFullViewUK\/","https:\/\/www.youtube.com\/channel\/UC6Xt_hNdoAmVmHvMHpNxiIA"]},{"@type":"Person","@id":"https:\/\/blog.id-direct.com\/fr-be\/#\/schema\/person\/abaa9575b453f8387f3e02330357299b","name":"iddirect"}]}},"_links":{"self":[{"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/posts\/3436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/comments?post=3436"}],"version-history":[{"count":0,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/posts\/3436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/media\/3454"}],"wp:attachment":[{"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/media?parent=3436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/categories?post=3436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.id-direct.com\/fr-be\/wp-json\/wp\/v2\/tags?post=3436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}